{"id":921,"date":"2019-01-06T13:31:34","date_gmt":"2019-01-06T04:31:34","guid":{"rendered":"https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480..jpg"},"modified":"2019-01-06T13:31:34","modified_gmt":"2019-01-06T04:31:34","slug":"20190105_13485126859770333108900480-jpg","status":"inherit","type":"attachment","link":"https:\/\/oze-fujiya.com\/wordpress\/20190105_13485126859770333108900480-jpg\/","title":{"rendered":"20190105_13485126859770333108900480..jpg"},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"vkexunit_cta_each_option":""},"class_list":["post-921","attachment","type-attachment","status-inherit","hentry"],"smush":{"stats":{"time":0.27,"bytes":6430,"percent":2.62,"size_before":244987,"size_after":238557,"lossy":0,"keep_exif":0,"api_version":"1.0"},"sizes":{"post-thumbnail":{"time":0.01,"bytes":450,"percent":3.47,"size_before":12958,"size_after":12508},"media_thumbnail":{"time":0.02,"bytes":1066,"percent":2.78,"size_before":38316,"size_after":37250},"medium":{"time":0.03,"bytes":576,"percent":3.69,"size_before":15626,"size_after":15050},"thumbnail":{"time":0.04,"bytes":316,"percent":4.86,"size_before":6496,"size_after":6180},"large":{"time":0.03,"bytes":2481,"percent":2.38,"size_before":104415,"size_after":101934},"medium_large":{"time":0.14,"bytes":1541,"percent":2.29,"size_before":67176,"size_after":65635}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480..jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480.-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480.-300x225.jpg 300w, https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480.-768x576.jpg 768w, https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480.-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":3000,"height":2250,"file":"2019\/01\/20190105_13485126859770333108900480..jpg","sizes":{"thumbnail":{"file":"20190105_13485126859770333108900480.-150x150.jpg","width":150,"height":150,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480.-150x150.jpg"},"medium":{"file":"20190105_13485126859770333108900480.-300x225.jpg","width":300,"height":225,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480.-300x225.jpg"},"medium_large":{"file":"20190105_13485126859770333108900480.-768x576.jpg","width":768,"height":576,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480.-768x576.jpg"},"large":{"file":"20190105_13485126859770333108900480.-1024x768.jpg","width":1024,"height":768,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480.-1024x768.jpg"},"media_thumbnail":{"file":"20190105_13485126859770333108900480.-600x371.jpg","width":600,"height":371,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480.-600x371.jpg"},"post-thumbnail":{"file":"20190105_13485126859770333108900480.-320x180.jpg","width":320,"height":180,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480.-320x180.jpg"},"full":{"file":"20190105_13485126859770333108900480..jpg","width":3000,"height":2250,"mime_type":"image\/jpeg","source_url":"https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480..jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"filesize":763455},"post":null,"source_url":"https:\/\/oze-fujiya.com\/wordpress\/wp-content\/uploads\/2019\/01\/20190105_13485126859770333108900480..jpg","_links":{"self":[{"href":"https:\/\/oze-fujiya.com\/wordpress\/wp-json\/wp\/v2\/media\/921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oze-fujiya.com\/wordpress\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/oze-fujiya.com\/wordpress\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/oze-fujiya.com\/wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/oze-fujiya.com\/wordpress\/wp-json\/wp\/v2\/comments?post=921"}]}}